{"id":18991,"date":"2022-10-05T10:21:43","date_gmt":"2022-10-05T02:21:43","guid":{"rendered":"https:\/\/vn.karmamedical.com\/danh-sach-cua-hang-xe-lan-karma\/"},"modified":"2023-03-22T13:58:03","modified_gmt":"2023-03-22T05:58:03","slug":"danh-sach-cua-hang-xe-lan-karma","status":"publish","type":"page","link":"https:\/\/vn.karmamedical.com\/en\/danh-sach-cua-hang-xe-lan-karma\/","title":{"rendered":"Where To Buy"},"content":{"rendered":"\t<section class=\"section\" id=\"section_1567920427\">\n\t\t<div class=\"bg section-bg fill bg-fill  \" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div><!-- .section-bg -->\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-middle align-center\"  id=\"row-1712128102\">\n<div class=\"col page_head small-12 large-12\"  ><div class=\"col-inner text-center\" style=\"padding:200px 0px 0px 0px;margin:15px 0px -30px 0px;\" >\n<h1 style=\"color: #fff; font-weight: 400; letter-spacing: 0.025em; font-size: 48px; text-shadow: black 0 0 0.6em;\">Where to Buy<\/h1>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n\t\t<\/div><!-- .section-content -->\n\n\t\t\n<style scope=\"scope\">\n\n#section_1567920427 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n#section_1567920427 .section-bg.bg-loaded {\n  background-image: url(https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/11\/\u92b7\u552e\u64da\u9ede.jpg);\n}\n#section_1567920427 .section-bg {\n  background-position: 0% 5%;\n}\n\n\n@media (min-width:550px) {\n\n  #section_1567920427 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n\n}\n\n\n@media (min-width:850px) {\n\n  #section_1567920427 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1751265520\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div><!-- .section-bg -->\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-collapse align-center\"  id=\"row-1423783857\">\n<div class=\"col medium-9 small-11 large-12\"  ><div class=\"col-inner text-left\"  >\n<h3>Find your nearest dealer to buy our fantastic wheelchair products or order directly through <span style=\"text-decoration: underline;\"><span style=\"color: #00a096;\"><strong><a style=\"color: #00a096; text-decoration: underline;\" href=\"https:\/\/bit.ly\/3sqQTdm\" target=\"_blank\" rel=\"noopener\">Shopee<\/a><\/strong><\/span><\/span>:<\/h3>\n<div id=\"store_locator\" class=\"store_locator modal-body\"><div class=\"store-locator-row\"><div id=\"store_locator_sidebar\" class=\"store_locator_sidebar store-locator-col-xs-12 store-locator-col-sm-12 store-locator-col-md-3 store-locator-pull-left\"><div id=\"store_locator_sidebar_content\" class=\"store_locator_sidebar_content store-locator-row\">    <div id=\"store_locator_search_box\" class=\"store_locator_search_box store-locator-col-xs-12 store-locator-col-sm-12 \"><div class=\"store-locator-row\"><div class=\"store-locator-col-xs-12 store-locator-col-sm-12\">                                                            <span id=\"store_locator_filter_active_filter_box\" class=\"store_locator_filter_active_filter_box\">   <small>Active Filter:<\/small> <span id=\"store_locator_filter_active_filter\"><\/span>                    <\/span>                    <\/div><\/div><div class=\"store-locator-row\"><div class=\"store-locator-col-xs-12 store-locator-col-sm-12\"><input id=\"store_locator_address_field\" class=\"store_locator_address_field\" type=\"text\" name=\"location\" placeholder=\"Enter your address\">                                                            <\/div><\/div>                        <div class=\"store-locator-row\"><div id=\"store_locator_filter\" class=\"store_locator_filter\"><div id=\"store_locator_filter_open_close\" class=\"store_locator_filter_open_close store-locator-col-xs-12 store-locator-col-sm-12\"><h3 class=\"store_locator_filter_title\">Filter<\/h3> <i class=\"fa fa-chevron-down text-right\"><\/i><\/div><div id=\"store_locator_filter_content\" class=\"store_locator_filter_content\" style=\"display: block;\"><div class=\"store-locator-col-xs-12 store-locator-col-sm-12 single_filter\">                    <select name=\"categories\" id=\"store_locator_filter_categories\" class=\"select store_locator_filter_categories\">                        <option value=\"\">Select a Category<\/option>    <option value=\"284\" selected=\"selected\" data-icon=\"\">C\u1eeda H\u00e0ng Y T\u1ebf<\/option><\/select>                    <\/div><div class=\"store-locator-col-xs-12 store-locator-col-sm-12 single_filter\"><h5>Radius<\/h5><select name=\"radius\" id=\"store_locator_filter_radius\" class=\"select store_locator_filter_radius\"><option value=\"\" > mi<\/option><\/select><\/div><div class=\"store-locator-col-xs-12 store-locator-col-sm-12 single_filter\"><h5>the Region<\/h5><label class=\"single_filter_checkbox control control--checkbox\"><input  name=\"345\" type=\"checkbox\" class=\"store_locator_filter_checkbox\" value=\"\u0110\u1ed3ng Nai\">\u0110\u1ed3ng Nai<div class=\"control__indicator\"><\/div><\/label><label class=\"single_filter_checkbox control control--checkbox\"><input  name=\"283\" type=\"checkbox\" class=\"store_locator_filter_checkbox\" value=\"H\u00e0 N\u1ed9i\">H\u00e0 N\u1ed9i<div class=\"control__indicator\"><\/div><\/label><label class=\"single_filter_checkbox control control--checkbox\"><input  name=\"285\" type=\"checkbox\" class=\"store_locator_filter_checkbox\" value=\"H\u00e0 T\u0129nh\">H\u00e0 T\u0129nh<div class=\"control__indicator\"><\/div><\/label><label class=\"single_filter_checkbox control control--checkbox\"><input  name=\"344\" type=\"checkbox\" class=\"store_locator_filter_checkbox\" value=\"H\u1ea3i Ph\u00f2ng\">H\u1ea3i Ph\u00f2ng<div class=\"control__indicator\"><\/div><\/label><label class=\"single_filter_checkbox control control--checkbox\"><input  name=\"286\" type=\"checkbox\" class=\"store_locator_filter_checkbox\" value=\"Th\u00e0nh Ph\u1ed1 H\u1ed3 Ch\u00ed Minh\">Th\u00e0nh Ph\u1ed1 H\u1ed3 Ch\u00ed Minh<div class=\"control__indicator\"><\/div><\/label><\/div><\/div><\/div><\/div>            <\/div><div id=\"store_locator_result_list_box\" class=\"store_locator_result_list_box store-locator-col-xs-12 store-locator-col-sm-12\">            <hr class=\"grey\">            <div id=\"store_locator_result_list\">                            <\/div><\/div><\/div><\/div><div id=\"store_locator_main\" class=\"store_locator_main  store-locator-col-xs-12 store-locator-col-sm-12 store-locator-col-md-6\"><div id=\"store_locator_map\" style=\"height: 100%;\"><\/div>                    <div id=\"store_locator_dragged_button\" class=\"btn button et_pb_button button-primary theme-button store_locator_dragged_button\">                        Search in this Area                    <\/div><\/div>    <\/div>            <button type=\"button\" id=\"store_modal_close\" class=\"store_modal_close\" data-dismiss=\"modal\" aria-label=\"Close\"><span aria-hidden=\"true\">&times;<\/span><\/button><div id=\"store_locator_loading\" class=\"store_locator_loading store-locator-hidden\"><i class=\"fa fa fa-spinner fa-spin fa-3x\"><\/i><\/div><\/div>\n<\/div><\/div>\n\n<style scope=\"scope\">\n\n<\/style>\n<\/div>\n\t\t<\/div><!-- .section-content -->\n\n\t\t\n<style scope=\"scope\">\n\n#section_1751265520 {\n  padding-top: 65px;\n  padding-bottom: 65px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-bold-center\"><b><\/b><span class=\"section-title-main\" style=\"color:rgb(0, 161, 150);\">Products<\/span><b><\/b><\/h3><\/div><!-- .section-title -->\n\n  \n    <div class=\"row large-columns-4 medium-columns- small-columns-2 row-small slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n  \t\n\t     \n\t\t\t\t\t\n<div class=\"product-small col has-hover product type-product post-19066 status-publish first instock product_cat-transfer-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/vn.karmamedical.com\/en\/product\/km-1520-3\/\">\n\t\t\t\t\t<img width=\"300\" height=\"274\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-125Q24-1050x960-side-300x274.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-125Q24-1050x960-side-300x274.png 300w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-125Q24-1050x960-side-768x702.png 768w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-125Q24-1050x960-side-1024x936.png 1024w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-125Q24-1050x960-side-600x549.png 600w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-125Q24-1050x960-side.png 1050w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img width=\"300\" height=\"274\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-Ergo-125-F-1050x960-0810-300x274.png\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-Ergo-125-F-1050x960-0810-300x274.png 300w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-Ergo-125-F-1050x960-0810-768x702.png 768w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-Ergo-125-F-1050x960-0810-1024x936.png 1024w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-Ergo-125-F-1050x960-0810-600x549.png 600w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/S-Ergo-125-F-1050x960-0810.png 1050w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><!-- box-image -->\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div>\t\t<\/div><!-- box-text -->\n\t<\/div><!-- box -->\n\t\t<\/div><!-- .col-inner -->\n<\/div><!-- col -->\n\t            \n\t\t\t\t\t\n<div class=\"product-small col has-hover product type-product post-18983 status-publish instock product_cat-transfer-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/vn.karmamedical.com\/en\/product\/agl\/\">\n\t\t\t\t\t<img width=\"300\" height=\"274\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW1_1050x960_S-award-en-300x274.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW1_1050x960_S-award-en-300x274.png 300w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW1_1050x960_S-award-en-768x702.png 768w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW1_1050x960_S-award-en-1024x936.png 1024w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW1_1050x960_S-award-en-600x549.png 600w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW1_1050x960_S-award-en.png 1050w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img width=\"300\" height=\"274\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW_1050x960_F-award-en-300x274.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW_1050x960_F-award-en-300x274.jpg 300w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW_1050x960_F-award-en-768x702.jpg 768w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW_1050x960_F-award-en-1024x936.jpg 1024w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW_1050x960_F-award-en-600x549.jpg 600w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2019\/12\/AGL-TW_1050x960_F-award-en.jpg 1050w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><!-- box-image -->\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div>\t\t<\/div><!-- box-text -->\n\t<\/div><!-- box -->\n\t\t<\/div><!-- .col-inner -->\n<\/div><!-- col -->\n\t            \n\t\t\t\t\t\n<div class=\"product-small col has-hover product type-product post-19067 status-publish last instock product_cat-travel-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/vn.karmamedical.com\/en\/product\/km-2501\/\">\n\t\t\t\t\t<img width=\"300\" height=\"274\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2025\/02\/Ergo-Lite-S-300x274_2025.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><img width=\"300\" height=\"274\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2025\/02\/Ergo-Lite-L-300x274_2025.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><!-- box-image -->\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div>\t\t<\/div><!-- box-text -->\n\t<\/div><!-- box -->\n\t\t<\/div><!-- .col-inner -->\n<\/div><!-- col -->\n\t            \n\t\t\t\t\t\n<div class=\"product-small col has-hover product type-product post-19063 status-publish first instock product_cat-transfer-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/vn.karmamedical.com\/en\/product\/sm-250-5\/\">\n\t\t\t\t\t<img width=\"300\" height=\"274\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2021\/11\/SM-250-purple-white-frame-tw2019-1050x960_L-1-300x274.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2021\/11\/SM-250-purple-white-frame-tw2019-1050x960_L-1-300x274.jpg 300w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2021\/11\/SM-250-purple-white-frame-tw2019-1050x960_L-1-1024x936.jpg 1024w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2021\/11\/SM-250-purple-white-frame-tw2019-1050x960_L-1-768x702.jpg 768w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2021\/11\/SM-250-purple-white-frame-tw2019-1050x960_L-1-600x549.jpg 600w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2021\/11\/SM-250-purple-white-frame-tw2019-1050x960_L-1.jpg 1050w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img width=\"300\" height=\"248\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2021\/10\/SM-250.5-550x455-F-Silver-White-300x248.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2021\/10\/SM-250.5-550x455-F-Silver-White-300x248.jpg 300w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2021\/10\/SM-250.5-550x455-F-Silver-White.jpg 550w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><!-- box-image -->\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div>\t\t<\/div><!-- box-text -->\n\t<\/div><!-- box -->\n\t\t<\/div><!-- .col-inner -->\n<\/div><!-- col -->\n\t            \n\t\t\t\t\t\n<div class=\"product-small col has-hover product type-product post-19064 status-publish instock product_cat-standard-en has-post-thumbnail shipping-taxable product-type-grouped\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/vn.karmamedical.com\/en\/product\/sm-150-5\/\">\n\t\t\t\t\t<img width=\"300\" height=\"274\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-1050x960-S-300x274.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-1050x960-S-300x274.png 300w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-1050x960-S-768x702.png 768w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-1050x960-S-1024x936.png 1024w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-1050x960-S-600x549.png 600w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-1050x960-S.png 1050w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img width=\"300\" height=\"274\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-F-1050x906-0810-300x274.png\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-F-1050x906-0810-300x274.png 300w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-F-1050x906-0810-768x702.png 768w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-F-1050x906-0810-1024x936.png 1024w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-F-1050x906-0810-600x549.png 600w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2018\/08\/SM-150.5-F-1050x906-0810.png 1050w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><!-- box-image -->\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div>\t\t<\/div><!-- box-text -->\n\t<\/div><!-- box -->\n\t\t<\/div><!-- .col-inner -->\n<\/div><!-- col -->\n\t            \n\t\t\t\t\t\n<div class=\"product-small col has-hover product type-product post-19260 status-publish last instock product_cat-spare-parts-accessories has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/vn.karmamedical.com\/en\/product\/ban-an\/\">\n\t\t\t\t\t<img width=\"300\" height=\"296\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/table-tray-300x296.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/table-tray-300x296.png 300w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/table-tray-768x757.png 768w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/table-tray-600x591.png 600w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/table-tray-100x100.png 100w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/table-tray.png 907w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><!-- box-image -->\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div>\t\t<\/div><!-- box-text -->\n\t<\/div><!-- box -->\n\t\t<\/div><!-- .col-inner -->\n<\/div><!-- col -->\n\t            \n\t\t\t\t\t\n<div class=\"product-small col has-hover product type-product post-19261 status-publish first instock product_cat-spare-parts-accessories has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/vn.karmamedical.com\/en\/product\/dai-an-toan\/\">\n\t\t\t\t\t<img width=\"300\" height=\"274\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/Pelvic-Belt-300x274.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/Pelvic-Belt-300x274.png 300w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/Pelvic-Belt-1024x936.png 1024w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/Pelvic-Belt-768x702.png 768w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/Pelvic-Belt-600x549.png 600w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/Pelvic-Belt.png 1050w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><!-- box-image -->\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div>\t\t<\/div><!-- box-text -->\n\t<\/div><!-- box -->\n\t\t<\/div><!-- .col-inner -->\n<\/div><!-- col -->\n\t            \n\t\t\t\t\t\n<div class=\"product-small col has-hover product type-product post-19263 status-publish instock product_cat-spare-parts-accessories has-post-thumbnail shipping-taxable product-type-simple\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n<\/div>\n\t<div class=\"product-small box \">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/vn.karmamedical.com\/en\/product\/khay-dung-coc-nuoc\/\">\n\t\t\t\t\t<img width=\"300\" height=\"274\" src=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/TW-cup-holder-1050x960-1-300x274.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/TW-cup-holder-1050x960-1-300x274.png 300w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/TW-cup-holder-1050x960-1-1024x936.png 1024w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/TW-cup-holder-1050x960-1-768x702.png 768w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/TW-cup-holder-1050x960-1-600x549.png 600w, https:\/\/vn.karmamedical.com\/wp-content\/uploads\/2022\/02\/TW-cup-holder-1050x960-1.png 1050w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><!-- box-image -->\n\n\t\t<div class=\"box-text box-text-products text-center grid-style-2\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div>\t\t<\/div><!-- box-text -->\n\t<\/div><!-- box -->\n\t\t<\/div><!-- .col-inner -->\n<\/div><!-- col -->\n\t            \n\t        <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":53,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/vn.karmamedical.com\/en\/wp-json\/wp\/v2\/pages\/18991"}],"collection":[{"href":"https:\/\/vn.karmamedical.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vn.karmamedical.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vn.karmamedical.com\/en\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/vn.karmamedical.com\/en\/wp-json\/wp\/v2\/comments?post=18991"}],"version-history":[{"count":3,"href":"https:\/\/vn.karmamedical.com\/en\/wp-json\/wp\/v2\/pages\/18991\/revisions"}],"predecessor-version":[{"id":18994,"href":"https:\/\/vn.karmamedical.com\/en\/wp-json\/wp\/v2\/pages\/18991\/revisions\/18994"}],"wp:attachment":[{"href":"https:\/\/vn.karmamedical.com\/en\/wp-json\/wp\/v2\/media?parent=18991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}